{"id":4405,"date":"2024-09-09T09:20:30","date_gmt":"2024-09-09T07:20:30","guid":{"rendered":"https:\/\/vss.michaelschaedler.li\/participer\/"},"modified":"2026-06-16T11:31:12","modified_gmt":"2026-06-16T09:31:12","slug":"mitmachen","status":"publish","type":"page","link":"https:\/\/vss-unes.ch\/fr\/mitmachen\/","title":{"rendered":"Participer"},"content":{"rendered":"<section class=\"gb-container gb-container-46287441\">\n<div class=\"gb-container gb-container-2a48dc36 gbp-section\">\n\n<h1 class=\"gb-headline gb-headline-1512e882 gb-headline-text gbp-section__headline\">Participer<\/h1>\n\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-e6d4e90e gbp-section\">\n<div class=\"gb-container gb-container-69c2ebac gbp-section__inner\">\n\n<p class=\"gb-headline gb-headline-1c6a282c gb-headline-text gbp-section__headline\"><strong>Toi aussi, fais entendre la voix des \u00e9tudiant\u00b7e\u00b7s !<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous fa\u00e7onnons les conditions d&#8217;\u00e9tudes de demain gr\u00e2ce aux id\u00e9es des \u00e9tudiant\u00b7e\u00b7s qui s&#8217;engagent \u00e0 nos c\u00f4t\u00e9s ! <br>Tu veux contribuer \u00e0 fa\u00e7onner le pr\u00e9sent et l&#8217;avenir du paysage universitaire suisse ? Alors engage-toi au sein de l&#8217;UNES ! <\/p>\n\n<\/div>\n<\/section>\n\n<div class=\"gb-container gb-container-3362119e gbp-section\" id=\"vorstand\">\n<div class=\"gb-container gb-container-982ab54b\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-9f13b323\">\n<div class=\"gb-grid-column gb-grid-column-18104176\"><div class=\"gb-container gb-container-18104176\">\n\n<h2 class=\"gb-headline gb-headline-c2c5c55f gb-headline-text gbp-section__headline\">Comit\u00e9 ex\u00e9cutif<\/h2>\n\n\n<div class=\"gb-container gb-container-abe83b3a\">\n\n<div class=\"gb-headline gb-headline-4c1c2a2b gb-headline-text gbp-section__text\">Le Comit\u00e9 ex\u00e9cutif de l&#8217;UNES est l&#8217;organe ex\u00e9cutif de l&#8217;association.&nbsp; En tant que membre du Comit\u00e9 ex\u00e9cutif, tu fais partie d&#8217;une \u00e9quipe de 7 personnes charg\u00e9e de la direction strat\u00e9gique de l&#8217;association et de la mise en \u0153uvre des d\u00e9cisions de l&#8217;Assembl\u00e9e des d\u00e9l\u00e9gu\u00e9\u00b7e\u00b7s et du Conseil des Sections.<br>Implique-toi, d\u00e9veloppe avec nous des id\u00e9es, des visions et des revendications. Repr\u00e9sente l&#8217;association et les \u00e9tudiant\u00b7e\u00b7s des hautes \u00e9coles suisses lors de conf\u00e9rences nationales et internationales, r\u00e9dige des articles, parle de nous. Participe \u00e0 des \u00e9v\u00e9nements tels que des tables rondes sur des th\u00e8mes li\u00e9s \u00e0 la politique des hautes \u00e9coles ou encore \u00e0 des flashmobs, mobilise les \u00e9tudiant\u00b7e\u00b7s autour de th\u00e8mes li\u00e9s \u00e0 la politique des hautes \u00e9coles. Il n&#8217;y a aucune limite \u00e0 tes id\u00e9es !<br><br>   <\/div>\n\n<\/div>\n\n\n<a class=\"gb-button gb-button-43eb71b6 gbp-button--primary\" href=\"mailto:info@vss-unes.ch?subject=Mitarbeit%20im%20Vorstand\"><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg><\/span><span class=\"gb-button-text\">Participer<\/span><\/a>\n\n\n<div class=\"gb-container gb-container-8bd6132e gb-accordion\">\n<div class=\"gb-container gb-container-01690254 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-486c7bca gb-accordion__toggle\" id=\"gb-accordion-toggle-486c7bca\"><span class=\"gb-button-text\">FAQ sur le Comit\u00e9 ex\u00e9cutif<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-9912cdff\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-9912cdff\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4cf8f232\">\n<div class=\"gb-grid-column gb-grid-column-4a6a395c\"><div class=\"gb-container gb-container-4a6a395c\">\n\n<p class=\"wp-block-paragraph\"><strong>C\u2019est quoi, le Comit\u00e9 ex\u00e9cutif ? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Comit\u00e9 ex\u00e9cutif est l\u2019ex\u00e9cutif de l\u2019union. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Que fait le Comit\u00e9 ex\u00e9cutif de l\u2019UNES ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que membre du Comit\u00e9 ex\u00e9cutif, tu diriges l\u2019union dans une \u00e9quipe de 7 personnes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quels sont les avantages pour moi ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant ton mandat au sein du Comit\u00e9, tu seras impliqu\u00e9 dans de nombreux projets et tu apprendras \u00e9norm\u00e9ment au sein d&#8217;une \u00e9quipe motiv\u00e9e, notamment en mati\u00e8re de gestion de projet, de lobbying, de gestion du personnel, de rh\u00e9torique et bien plus encore. Les t\u00e2ches d\u00e9pendent du dossier trait\u00e9.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quel temps et quelle charge de travail dois-je pr\u00e9voir ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La charge de travail au sein du Comit\u00e9 ex\u00e9cutif n&#8217;est pas n\u00e9gligeable, mais elle est facilement compatible avec les \u00e9tudes. Une exp\u00e9rience pr\u00e9alable dans une section ou une association \u00e9tudiante de ta haute \u00e9cole est un atout, mais n&#8217;est pas indispensable.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tu souhaites en savoir plus sur le travail du Comit\u00e9 ex\u00e9cutif ? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors passe nous voir \u00e0 Berne, appelle-nous ou envoie-nous un e-mail.<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-7e2fb4e4\"><div class=\"gb-container gb-container-7e2fb4e4\">\n\n<div style=\"position: relative; width: 100%; height: auto;\">\n  <img decoding=\"async\" src=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2025\/06\/970ca520-3f87-4c1e-8c27-9bb70d9c714e.jpg\" style=\"width: 100%; display: block;\"\/>\n  <img decoding=\"async\" src=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2025\/07\/vorstand_fun.jpg\" style=\"width: 100%; display: block; position: absolute; top: 0; left: 0; opacity: 0; transition: opacity 0.4s;\" onmouseover=\"this.style.opacity=1\" onmouseout=\"this.style.opacity=0\"\/>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-cf1e4c1c\"><div class=\"gb-container gb-container-cf1e4c1c\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<section class=\"gb-container gb-container-e6ba7797 gbp-section\">\n<div class=\"gb-container gb-container-80220d25 gbp-section__inner\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-93fe63c1\">\n<div class=\"gb-grid-column gb-grid-column-b3d945f7\"><div class=\"gb-container gb-container-b3d945f7\">\n\n<h2 class=\"gb-headline gb-headline-87ee3f8e gb-headline-text gbp-section__headline\">Commissions et groupes de travail<\/h2>\n\n\n<div class=\"gb-container gb-container-2055ee7a\">\n\n<div class=\"gb-headline gb-headline-0a8f0932 gb-headline-text gbp-section__text\">L&#8217;\u00e9galit\u00e9 est-elle un sujet important dans ta haute \u00e9cole ? Tu penses que les hautes \u00e9coles devraient montrer l&#8217;exemple en mati\u00e8re de d\u00e9veloppement durable ? Tu souhaites t&#8217;engager pour que nous participions \u00e0 nouveau au programme Erasmus+ ?  <br><strong>Engage-toi dans les diff\u00e9rentes commissions et fa\u00e7onne ainsi toi-m\u00eame tes conditions d&#8217;\u00e9tudes !&nbsp;<\/strong><\/div>\n\n\n\n<a class=\"gb-button gb-button-fbd4ac68 gbp-button--primary\" href=\"mailto:info@vss-unes.ch\"><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg><\/span><span class=\"gb-button-text\">Participer<\/span><\/a>\n\n<\/div>\n\n<div class=\"gb-container gb-container-23d12e8a gb-accordion\"><\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-e7776628\"><div class=\"gb-container gb-container-e7776628\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-1a33b5ac\">\n<div class=\"gb-grid-column gb-grid-column-81fd70b2\"><div class=\"gb-container gb-container-81fd70b2\"><a class=\"gb-container-link\" href=\"https:\/\/vss-unes.ch\/soko\"><\/a>\n\n<p class=\"gb-headline gb-headline-3f816549 gb-headline-text\"><strong>Commission Sociale (CoSo)<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-fb9310a4\"><div class=\"gb-container gb-container-fb9310a4\"><a class=\"gb-container-link\" href=\"https:\/\/vss-unes.ch\/coedg\/\"><\/a>\n\n<p class=\"gb-headline gb-headline-3ccab86d gb-headline-text\"><strong>Commission d\u2019Egalit\u00e9 (CodEg)<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-141c3a11\"><div class=\"gb-container gb-container-141c3a11\"><a class=\"gb-container-link\" href=\"https:\/\/vss-unes.ch\/hopoko\/\"><\/a>\n\n<p class=\"gb-headline gb-headline-982bf95a gb-headline-text\"><strong>Commission de la politique des hautes \u00e9coles (HopoKo)<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-933643c0\"><div class=\"gb-container gb-container-933643c0\"><a class=\"gb-container-link\" href=\"https:\/\/vss-unes.ch\/solic\/\"><\/a>\n\n<p class=\"gb-headline gb-headline-c022c4e8 gb-headline-text\"><strong>Commission internationale et de solidarit\u00e9 (SOLIC)<\/strong><\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<div class=\"gb-container gb-container-c36218a2 gbp-section\" id=\"vorstand\">\n<div class=\"gb-container gb-container-abe70c42\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-11e9a5dd\">\n<div class=\"gb-grid-column gb-grid-column-74e8eb10\"><div class=\"gb-container gb-container-74e8eb10\">\n\n<h2 class=\"gb-headline gb-headline-ffc1cb28 gb-headline-text gbp-section__headline\"><strong>\u00c9tudiant\u00b7e\u00b7s pour des proc\u00e9dures d\u2019accr\u00e9ditation<\/strong>&nbsp;<\/h2>\n\n\n<div class=\"gb-container gb-container-67519792\">\n\n<div class=\"gb-headline gb-headline-2a8b5e6b gb-headline-text gbp-section__text\">Les hautes \u00e9coles suisses sont r\u00e9guli\u00e8rement \u00e9valu\u00e9es afin de v\u00e9rifier comment elles assurent la qualit\u00e9 des \u00e9tudes, de l\u2019enseignement et de leurs structures institutionnelles. Les accr\u00e9ditations confirment qu\u2019une haute \u00e9cole ou qu\u2019un programme d\u2019\u00e9tudes r\u00e9pond aux standards de qualit\u00e9. Dans la proc\u00e9dure d\u2019accr\u00e9ditation, une personne \u00e9tudiante fait \u00e9galement partie du groupe d\u2019expert\u00b7e\u00b7s \u2013 peut-\u00eatre bient\u00f4t toi ?  <\/div>\n\n\n\n<a class=\"gb-button gb-button-e4993cfa gb-button-text gbp-button--primary\" href=\"https:\/\/vss-unes.ch\/fr\/recherche-etudiant%c2%b7e%c2%b7s-pour-des-procedures-daccreditation\/\">Participer<\/a>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br><br><\/p>\n\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-4f090396\"><div class=\"gb-container gb-container-4f090396\">\n<div class=\"gb-container gb-container-25fbb167 gb-accordion\">\n<div class=\"gb-container gb-container-843afbe3 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-ec42df2b gb-accordion__toggle\" id=\"gb-accordion-toggle-ec42df2b\"><span class=\"gb-button-text\">Aucune exp\u00e9rience requise<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-613722f0\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-613722f0\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-8b88e8ca\">\n<div class=\"gb-grid-column gb-grid-column-13128c62\"><div class=\"gb-container gb-container-13128c62\">\n\n<p class=\"wp-block-paragraph\">Aucune connaissance pr\u00e9alable n\u2019est n\u00e9cessaire \u2013 avec de l\u2019int\u00e9r\u00eat pour l\u2019\u00e9ducation, de la motivation et la formation de l&#8217;UNES, tu es bien pr\u00e9par\u00e9\u00b7e. <br><br>Ensuite, tu seras int\u00e9gr\u00e9\u00b7e dans le pool d\u2019accr\u00e9ditation de l&#8217;UNES, o\u00f9 tu recevras r\u00e9guli\u00e8rement des informations sur les proc\u00e9dures ouvertes en Suisse et \u00e0 l\u2019\u00e9tranger en Europe, auxquelles tu pourras postuler. <\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-8ad13fcd gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-c83cc5cb gb-accordion__toggle\" id=\"gb-accordion-toggle-c83cc5cb\"><span class=\"gb-button-text\">Tes avantages<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-9944cef7\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-9944cef7\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-6741d1cd\">\n<div class=\"gb-grid-column gb-grid-column-73c10381\"><div class=\"gb-container gb-container-73c10381\">\n\n<p class=\"wp-block-paragraph\"><strong>Ton engagement pour la qualit\u00e9 des hautes \u00e9coles<\/strong> <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un aper\u00e7u passionnant de l\u2019assurance qualit\u00e9 et du d\u00e9veloppement des hautes \u00e9coles <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9couverte d\u2019autres hautes \u00e9coles <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Possibilit\u00e9 de t\u2019engager pour un enseignement de qualit\u00e9 <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une r\u00e9mun\u00e9ration tr\u00e8s \u00e9quitable par proc\u00e9dure (CHF 1&#8217;200\u20132&#8217;400) <\/li>\n<\/ul>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<section class=\"gb-container gb-container-af0a354b gbp-section\" id=\"ausschreibungen\">\n<div class=\"gb-container gb-container-12607083 gbp-section__inner\">\n<div class=\"gb-container gb-container-96b73aad\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-80659b66\">\n<div class=\"gb-grid-column gb-grid-column-67c70dd1\"><div class=\"gb-container gb-container-67c70dd1\">\n\n<h2 class=\"gb-headline gb-headline-37b3bcd2 gb-headline-text gbp-section__headline\">Postes vacants<\/h2>\n\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-2e75a34d gb-query-loop-wrapper\">\n<div class=\"gb-grid-column gb-grid-column-9e278282 gb-query-loop-item post-24857 ausschreibungen type-ausschreibungen status-publish hentry\"><div class=\"gb-container gb-container-9e278282\"><a class=\"gb-container-link\" href=\"http:\/\/24856\"><\/a>\n\n<p class=\"gb-headline gb-headline-669ee918 gb-headline-text custom_non_underline\">Poste vacant<\/p>\n\n\n<h2 class=\"gb-headline gb-headline-f46368d0 gbp-section__headline gb-headline-text\">Appel \u00e0 candidatures pour la copr\u00e9sidence de la Commission <br\/>internationale et de solidarit\u00e9 (SOLIC) de l\u2019UNES<\/h2>\n\n<div class=\"gb-headline gb-headline-762b7057 gbp-section__headline gb-headline-text gbp-section__text\">La commission internationale et de solidarit\u00e9 (SOLIC) s&#8217;occupe de la solidarit\u00e9 estudiantine et de la <br \/>mise en r\u00e9seau internationale de l&#8217;UNES. La co-pr\u00e9sidence de la SOLIC est une fonction b\u00e9n\u00e9vole passionnante. Tu es responsable de la coordination, de la direction et de la pr\u00e9paration des r\u00e9unions de la commission et tu repr\u00e9sentes la commission \u00e0 l&#8217;int\u00e9rieur et \u00e0 l&#8217;ext\u00e9rieur de l&#8217;union. La co-pr\u00e9sidence de la commission si\u00e8ge dans les organes l\u00e9gislatifs de l&#8217;UNES. En outre, les co-pr\u00e9sident\u00b7e\u00b7s de toutes les commissions th\u00e9matiques se rencontrent r\u00e9guli\u00e8rement.    <\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9e278282 gb-query-loop-item post-24853 ausschreibungen type-ausschreibungen status-publish hentry\"><div class=\"gb-container gb-container-9e278282\"><a class=\"gb-container-link\" href=\"http:\/\/24852\"><\/a>\n\n<p class=\"gb-headline gb-headline-669ee918 gb-headline-text custom_non_underline\">Poste vacant<\/p>\n\n\n<h2 class=\"gb-headline gb-headline-f46368d0 gbp-section__headline gb-headline-text\">Appel \u00e0 candidatures pour la Co-pr\u00e9sidence de la Commission pour <br\/>les affaires sociales (SoKo) de l&#8217;UNES<\/h2>\n\n<div class=\"gb-headline gb-headline-762b7057 gbp-section__headline gb-headline-text gbp-section__text\">La commission pour les affaires sociales (SoKo) aborde et traite les th\u00e8mes actuels dans le domaine <br \/>social. La co-pr\u00e9sidence de la SoKo est une fonction b\u00e9n\u00e9vole passionnante. Tu es responsable de la <br \/>coordination, de la direction et de la pr\u00e9paration des r\u00e9unions de la commission et <br \/>tu repr\u00e9sentes la commission \u00e0 l&#8217;int\u00e9rieur et \u00e0 l&#8217;ext\u00e9rieur de l&#8217;union. La co-pr\u00e9sidence de la <br \/>commission si\u00e8ge dans les organes l\u00e9gislatifs de l&#8217;UNES. En outre, les co-pr\u00e9sident\u00b7e\u00b7s de <br \/>toutes les commissions th\u00e9matiques se rencontrent r\u00e9guli\u00e8rement.    <\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9e278282 gb-query-loop-item post-24849 ausschreibungen type-ausschreibungen status-publish hentry\"><div class=\"gb-container gb-container-9e278282\"><a class=\"gb-container-link\" href=\"http:\/\/24848\"><\/a>\n\n<p class=\"gb-headline gb-headline-669ee918 gb-headline-text custom_non_underline\">Poste vacant<\/p>\n\n\n<h2 class=\"gb-headline gb-headline-f46368d0 gbp-section__headline gb-headline-text\">Appel \u00e0 candidatures \u00e0 la copr\u00e9sidence du Conseil des sections<\/h2>\n\n<div class=\"gb-headline gb-headline-762b7057 gbp-section__headline gb-headline-text gbp-section__text\">La pr\u00e9sidence du Conseil des Sections est une fonction b\u00e9n\u00e9vole passionnante qui peut \u00eatre exerc\u00e9e <br \/>aussi bien seul\u00b7e qu\u2019en copr\u00e9sidence. Tu seras responsable de la pr\u00e9paration, de la convocation, de la <br \/>direction des r\u00e9unions et de l\u2019animation du Conseil des Sections, en \u00e9changeant avec le Comit\u00e9 Ex\u00e9cutif <br \/>et les sections (les membres ordinaires de l\u2019UNES). Le Conseil des Sections se r\u00e9unit en g\u00e9n\u00e9ral une <br \/>fois par mois, mais au moins neuf fois par an.  <\/div>\n<\/div><\/div>\n<\/div>\n\n\n<div class=\"gb-container gb-container-ba6b59e5\">\n\n<a class=\"gb-button gb-button-67c7f20c gbp-button--primary\" href=\"mailto:info@vss-unes.ch?subject=Bewerbung%20beim%20VSS\"><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg><\/span><span class=\"gb-button-text\">Postuler<\/span><\/a>\n\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-a585c401 gbp-section\">\n<div class=\"gb-container gb-container-58b6974e gbp-section__inner\">\n\n<h2 class=\"gb-headline gb-headline-2e47ffdb gb-headline-text gbp-section__headline\">Autres moyens de s\u2019impliquer<\/h2>\n\n\n<div class=\"gb-container gb-container-c2707659 gb-accordion\">\n<div class=\"gb-container gb-container-23ebd967 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-4ac00ea1 gb-accordion__toggle\" id=\"gb-accordion-toggle-4ac00ea1\"><span class=\"gb-button-text\">\u00c9crits ton travail de Bachelor ou de Master chez nous !<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-b86193b6\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-b86193b6\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-67f077e5\">\n<div class=\"gb-grid-column gb-grid-column-d537ac40\"><div class=\"gb-container gb-container-d537ac40\">\n\n<p class=\"wp-block-paragraph\">De notre propre exp\u00e9rience, nous savons que la r\u00e9daction d\u2019un travail de Bachelor ou de Master est un grand d\u00e9fi. C\u2019est avec plaisir que nous te soutenons dans le choix d\u2019un sujet et des probl\u00e9matiques possibles pour un travail de Bachelor ou de Master dans un domaine pratique et passionnant ! <br><br>Es-tu \u00e0 la recherche d\u2019un sujet passionnant pour ton travail de Bachelor ou de Master ? Combine ton travail de Bachelor ou de Master avec ton travail sur ton avenir professionnel. \u00c0 l\u2019Union des \u00e9tudiant\u00b7e\u00b7s de Suisse (UNES) nous te soutenons dans ce projet, parce que notre champ d\u2019action couvre un large \u00e9ventail de sujets. Cela signifie que nous pouvons trouver des probl\u00e9matiques ou des sujets int\u00e9ressants pour des \u00e9tudiant\u00b7e\u00b7s de diff\u00e9rents cursus.    <\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Ci-dessous se trouvent quelques propositions et id\u00e9es (liste non exhaustive)<\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Psychologie de la motivation dans l\u2019engagement b\u00e9n\u00e9vole<\/li>\n\n\n\n<li>Gestion d\u2019une association \u00e0 but non lucratif<\/li>\n\n\n\n<li>Gestion du personnel<\/li>\n\n\n\n<li>Analyse historique des organisations d\u2019\u00e9tudiant\u00b7e\u00b7s en Suisse<\/li>\n\n\n\n<li>Sant\u00e9 psychique des \u00e9tudiant\u00b7e\u00b7s<\/li>\n\n\n\n<li>Analyse historique du syst\u00e8me des bourses d\u2019\u00e9tudes en Suisse<\/li>\n\n\n\n<li>Erasmus, le programme de mobilit\u00e9 europ\u00e9en et la Suisse<\/li>\n\n\n\n<li>Les \u00e9tudiant\u00b7e\u00b7s et leurs droits de participation dans les hautes \u00e9coles<\/li>\n\n\n\n<li>Possibilit\u00e9s de communication externes et internes pour les diff\u00e9rents groupes cibles dans le paysage des hautes \u00e9coles de Suisse<\/li>\n\n\n\n<li>Communication durable<\/li>\n\n\n\n<li>Structure et financement des organisations d\u2019\u00e9tudiant\u00b7e\u00b7s nationales en Europe<\/li>\n\n\n\n<li>Structure juridique d\u2019une ONG<\/li>\n\n\n\n<li>M\u00e9thode de lev\u00e9e de fonds dans une association<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si tu souhaites traiter ou analyser une probl\u00e9matique orient\u00e9e vers la pratique, que tu t\u2019int\u00e9resses \u00e9galement \u00e0 la structure et \u00e0 la vie quotidienne d\u2019une association nationale ainsi qu\u2019\u00e0 la perspective des hautes \u00e9coles et des \u00e9tudiant\u00b7e\u00b7s, alors contacte-nous ! Envoie simplement un email \u00e0 <a href=\"mailto:info@vss-unes.ch\">info@vss-unes.ch<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De notre propre exp\u00e9rience, nous savons que la r\u00e9daction d\u2019un travail de Bachelor ou de Master est un grand d\u00e9fi. C\u2019est avec plaisir que nous te soutenons dans le choix d\u2019un sujet et des probl\u00e9matiques possibles pour un travail de Bachelor ou de Master dans un domaine pratique passionnant. Ainsi, non seulement toi, mais \u00e9galement l\u2019UNES et les \u00e9tudiant\u00b7e\u00b7s d\u2019hier et demain, pourrez b\u00e9n\u00e9ficier des uns et des autres.  <\/p>\n\n\n\n<a class=\"gb-button gb-button-1ba97c1a gbp-button--primary\" href=\"mailto:info@vss-unes.ch?subject=Bachelor-%20oder%20Masterabeit%20beim%20VSS%20schreiben\"><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg><\/span><span class=\"gb-button-text\">Postuler<\/span><\/a>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-e90af0b0 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-12640656 gb-accordion__toggle\" id=\"gb-accordion-toggle-12640656\"><span class=\"gb-button-text\">R\u00e9seau des ancien\u00b7ne\u00b7s de l\u2019UNES<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-fca41796\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-fca41796\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-41dd42e9\">\n<div class=\"gb-grid-column gb-grid-column-064dff4b\"><div class=\"gb-container gb-container-064dff4b\">\n\n<p class=\"wp-block-paragraph\">Nous sommes extr\u00eamement reconnaissants de l\u2019engagement sans de toutes les personnes qui ont (ou ont eu) particip\u00e9 \u00e0 la vie de la f\u00e9d\u00e9ration. Afin de mettre en relation les personnes de toutes les g\u00e9n\u00e9rations qui ont \u00e9t\u00e9 actives au sein de la VSS, celle-ci entretient son r\u00e9seau d\u2019anciens membres. Si vous faites partie de ce r\u00e9seau et que vous souhaitez en savoir plus, vous pouvez contacter\u00a0<a href=\"mailto:info@vss-unes.ch\">info@vss-unes.ch<\/a>.<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-da60d9e6 gb-accordion__item\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-ef348871 gb-accordion__toggle\" id=\"gb-accordion-toggle-ef348871\"><span class=\"gb-button-text\">Contribution financi\u00e8re<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-ff60c97b\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-ff60c97b\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-83522cd7\">\n<div class=\"gb-grid-column gb-grid-column-5b88405d\"><div class=\"gb-container gb-container-5b88405d\">\n\n<p class=\"wp-block-paragraph\">L\u2019UNES est principalement financ\u00e9e par les cotisations des \u00e9tudiant\u00b7e\u00b7s. Nous sommes heureux\u00b7ses de recevoir des dons, petits et grands : <\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Coordonn\u00e9es bancaires<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">PostFinance<br>Compte postal: 30-28125-3<br>IBAN: CH08 0900 0000 3002 8125 3<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">En faveur de<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Verband der Schweizer Studierendenschaften (VSS), Bern<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participer Toi aussi, fais entendre la voix des \u00e9tudiant\u00b7e\u00b7s ! Nous fa\u00e7onnons les conditions d&#8217;\u00e9tudes de demain gr\u00e2ce aux id\u00e9es des \u00e9tudiant\u00b7e\u00b7s qui s&#8217;engagent \u00e0 nos c\u00f4t\u00e9s ! Tu veux &#8230; <a title=\"Participer\" class=\"read-more\" href=\"https:\/\/vss-unes.ch\/fr\/mitmachen\/\" aria-label=\"Read more about Participer\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4405","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/pages\/4405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/comments?post=4405"}],"version-history":[{"count":57,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/pages\/4405\/revisions"}],"predecessor-version":[{"id":24539,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/pages\/4405\/revisions\/24539"}],"wp:attachment":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/media?parent=4405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}