{"id":14684,"date":"2022-11-21T15:44:58","date_gmt":"2022-11-21T14:44:58","guid":{"rendered":"https:\/\/vss.michaelschaedler.li\/resolution-le-rencherissement-en-suisse\/"},"modified":"2022-11-21T15:44:58","modified_gmt":"2022-11-21T14:44:58","slug":"resolution-le-rencherissement-en-suisse","status":"publish","type":"post","link":"https:\/\/vss-unes.ch\/fr\/resolution-le-rencherissement-en-suisse\/","title":{"rendered":"R\u00e9solution \u00ab Le rench\u00e9rissement en Suisse \u00bb"},"content":{"rendered":"<p><em>Adopt\u00e9 le 6 novembre 2022 lors de la 179\u00e8me Assembl\u00e9e des D\u00e9l\u00e9gu\u00e9\u00b7e\u00b7s \u00e0 Neuch\u00e2tel.<br \/><\/em><\/p>\n<p>Les actuelles pr\u00e9visions \u00e9conomiques sont inqui\u00e9tantes pour la communaut\u00e9 estudiantine. En effet, nombreux sont les facteurs qui s\u2019accumulent et poussent une partie des \u00e9tudiant\u00b7e\u00b7s de notre pays dans des situations financi\u00e8res pr\u00e9caires. D\u2019aucuns voyaient la sortie de la pand\u00e9mie comme une d\u00e9livrance et un retour \u00e0 la normale, la r\u00e9alit\u00e9 nous montre qu\u2019il faut d\u00e9sormais faire face aux r\u00e9percussions \u00e9conomiques de cette derni\u00e8re. Viennent s\u2019ajouter \u00e0 cela, notamment : un contexte g\u00e9opolitique tendu en Europe concr\u00e9tis\u00e9 par la guerre en Ukraine, une p\u00e9nurie d\u2019\u00e9nergie ainsi qu\u2019une hausse in\u00e9dite des primes d\u2019assurances maladies (en moyenne 6,6 %) pour ce qui est de la Suisse.<\/p>\n<p>R\u00e9solution \u00ab <a href=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2022\/11\/2022-11-06_f_ResolutionInflation-1.pdf\" rel=\"noopener\" target=\"_blank\">Le rench\u00e9rissement en Suisse<\/a> \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adopt\u00e9 le 6 novembre 2022 lors de la 179\u00e8me Assembl\u00e9e des D\u00e9l\u00e9gu\u00e9\u00b7e\u00b7s \u00e0 Neuch\u00e2tel. Les actuelles pr\u00e9visions \u00e9conomiques sont inqui\u00e9tantes pour la communaut\u00e9 estudiantine. En effet, nombreux sont les facteurs &#8230; <a title=\"R\u00e9solution \u00ab Le rench\u00e9rissement en Suisse \u00bb\" class=\"read-more\" href=\"https:\/\/vss-unes.ch\/fr\/resolution-le-rencherissement-en-suisse\/\" aria-label=\"Read more about R\u00e9solution \u00ab Le rench\u00e9rissement en Suisse \u00bb\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[131],"tags":[],"class_list":["post-14684","post","type-post","status-publish","format-standard","hentry","category-resolutions"],"_links":{"self":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/posts\/14684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/comments?post=14684"}],"version-history":[{"count":0,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/posts\/14684\/revisions"}],"wp:attachment":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/media?parent=14684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/categories?post=14684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/tags?post=14684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}