{"id":4970,"date":"2024-07-18T08:48:16","date_gmt":"2024-07-18T06:48:16","guid":{"rendered":"https:\/\/vss.michaelschaedler.li\/themen\/durabilite\/"},"modified":"2026-06-24T10:49:34","modified_gmt":"2026-06-24T08:49:34","slug":"nachhaltigkeit","status":"publish","type":"themen","link":"https:\/\/vss-unes.ch\/fr\/themen\/nachhaltigkeit\/","title":{"rendered":"Durabilit\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les hautes \u00e9coles assument une lourde responsabilit\u00e9 sociale. Elles forment les futur\u00b7e\u00b7s d\u00e9cideuses et d\u00e9cideurs, \u00e0 travers la recherche elles g\u00e9n\u00e8rent des connaissances et des innovations et elles influencent l\u2019opinion publique. Pour l\u2019UNES, la durabilit\u00e9 dans les hautes \u00e9coles suisses signifie donc que la Conf\u00e9d\u00e9ration encourage la durabilit\u00e9 dans les hautes \u00e9coles avec des moyens financiers. Elle entend que les hautes \u00e9coles se d\u00e9veloppent de mani\u00e8re durable et que cela implique une coop\u00e9ration avec des organisations sp\u00e9cialis\u00e9es. L\u2019UNES s\u2019investit activement pour un fonctionnement durable des hautes \u00e9coles et suit ce sujet de mani\u00e8re intensive au sein du Groupe de travail \u00ab Durabilit\u00e9 \u00bb.   <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-1d8b337e\">\n<div class=\"gb-grid-column gb-grid-column-1759b312\"><div class=\"gb-container gb-container-1759b312\">\n\n<h2 class=\"wp-block-heading\"><strong>Notre vision<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">L&#8217;UNES s&#8217;engage en faveur d&#8217;un monde de l\u2019enseignement sup\u00e9rieur dans lequel la durabilit\u00e9 fait <strong>naturellement partie int\u00e9grante de l&#8217;\u00e9ducation, de la recherche et de la vie sur le campus.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">Les \u00e9tudiant-e-s sont habilit\u00e9-e-s \u00e0 participer activement \u00e0 la conception de leurs \u00e9tablissements d&#8217;enseignement sup\u00e9rieur (HEI) et \u00e0 promouvoir, en collaboration avec les acteur-rice-s concern\u00e9-e-s, une <strong>soci\u00e9t\u00e9 socialement juste, \u00e9cologiquement responsable et viable.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">La durabilit\u00e9 n&#8217;est pas seulement un mot d\u2019ordre politique, mais elle est \u00e9galement ancr\u00e9e dans le quotidien des \u00e9tudiant-e-s <strong>gr\u00e2ce \u00e0 des r\u00e9seaux solides, des structures participatives et des offres concr\u00e8tes.<\/strong> <\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;<\/p>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-06cc42fa\"><div class=\"gb-container gb-container-06cc42fa\">\n\n<h2 class=\"wp-block-heading\">Notre mission<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">L&#8217;UNES <strong>repr\u00e9sente les int\u00e9r\u00eats des \u00e9tudiant-e-s<\/strong> dans tous les domaines de la durabilit\u00e9 au niveau politique et <strong>permet aux \u00e9tudiant-e-s<\/strong> de s&#8217;engager efficacement en faveur du d\u00e9veloppement durable dans leurs hautes \u00e9coles. Gr\u00e2ce \u00e0 la mise en r\u00e9seau, <strong>\u00e0 la coop\u00e9ration avec les parties prenantes concern\u00e9es <\/strong>et \u00e0 <strong>des offres cibl\u00e9es<\/strong>, le ressort renforce le r\u00f4le des \u00e9tudiant-e-s en tant qu&#8217;acteur-trice-s actif-ve-s d&#8217;un monde des hautes \u00e9coles socialement \u00e9quitable et \u00e9cologiquement responsable.  <\/p>\n<\/blockquote>\n\n<\/div><\/div>\n<\/div>\n\n\n<figure class=\"gb-block-image gb-block-image-81ea753c\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1602\" class=\"gb-image gb-image-81ea753c\" src=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-scaled.jpeg\" alt=\"\" title=\"73db7d12-e07b-4069-97b2-c253b48b27d7neu\" srcset=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-scaled.jpeg 2560w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-300x188.jpeg 300w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-1024x641.jpeg 1024w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-768x481.jpeg 768w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-1536x961.jpeg 1536w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-2048x1282.jpeg 2048w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/73db7d12-e07b-4069-97b2-c253b48b27d7neu-2-1320x826.jpeg 1320w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\n<figcaption class=\"gb-headline gb-headline-e305d475 gb-headline-text\"><em>Photo: Ramon Lehmann<\/em><\/figcaption>\n<\/figure>\n\n\n<div class=\"gb-container gb-container-55c48ee4\">\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Priorit\u00e9s strat\u00e9giques<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Repr\u00e9sentation des int\u00e9r\u00eats politiques : <\/strong>l&#8217;UNES s&#8217;engage au niveau national en faveur d&#8217;une politique ambitieuse en mati\u00e8re de durabilit\u00e9 dans l&#8217;enseignement sup\u00e9rieur et int\u00e8gre les perspectives des \u00e9tudiant-e-s dans les processus politiques. <\/li>\n<\/ul>\n\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Repr\u00e9sentation des int\u00e9r\u00eats politiques : <\/strong>l&#8217;UNES s&#8217;engage au niveau national en faveur d&#8217;une politique ambitieuse en mati\u00e8re de durabilit\u00e9 dans l&#8217;enseignement sup\u00e9rieur et int\u00e8gre les perspectives des \u00e9tudiant-e-s dans les processus politiques. <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Soutien aux \u00e9tablissements d&#8217;enseignement sup\u00e9rieur :<\/strong> les \u00e9tudiant-e-s b\u00e9n\u00e9ficient d&#8217;un soutien pour s&#8217;impliquer dans les questions de durabilit\u00e9 au sein de leurs \u00e9tablissements, que ce soit dans des organes, des projets, des initiatives ou des processus strat\u00e9giques. <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Offres pour les \u00e9tudiant-e-s :<\/strong> l&#8217;UNES propose des ateliers, des formations continues, des guides, des formats d&#8217;\u00e9change ou d&#8217;autres offres qui renforcent l&#8217;engagement des \u00e9tudiant-e-s. <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mise en place d&#8217;un r\u00e9seau solide :<\/strong> l\u2019UNES met en relation les \u00e9tudiant-e-s, les associations \u00e9tudiantes et les acteur-trice-s du d\u00e9veloppement durable dans toute la Suisse, encourage les \u00e9changes et cr\u00e9e des synergies. <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Collaboration avec les parties prenantes :<\/strong> l&#8217;UNES collabore activement avec les hautes \u00e9coles, les associations, les ONG, les autorit\u00e9s et les expert-e-s afin de promouvoir ensemble le d\u00e9veloppement durable. <\/li>\n<\/ul>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1627\" src=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-scaled.jpeg\" alt=\"\" class=\"wp-image-24007\" style=\"aspect-ratio:1.7777777777777777;object-fit:cover;width:600px;height:auto\" srcset=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-scaled.jpeg 2560w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-300x191.jpeg 300w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-1024x651.jpeg 1024w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-768x488.jpeg 768w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-1536x976.jpeg 1536w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-2048x1302.jpeg 2048w, https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/8d3fce32-87d3-4c94-98a0-fca6b130917d-1320x839.jpeg 1320w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\"><em>Photo: Ramon Lehmann<\/em><\/figcaption><\/figure>\n<\/div>\n\n<div class=\"gb-container gb-container-25fbb167 gb-accordion\">\n<div class=\"gb-container gb-container-003ddc3e\">\n<div class=\"gb-container gb-container-3820a8f1 gb-accordion__item\">\n\n<button class=\"gb-button gb-button-dd0ab28b gb-accordion__toggle\" id=\"gb-accordion-toggle-dd0ab28b\"><span class=\"gb-button-text\">Revendications et d\u00e9finition des priorit\u00e9s du GT \u00ab Durabilit\u00e9 \u00bb (2021)<\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-72ede637\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-72ede637\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-89d20b04\">\n<div class=\"gb-grid-column gb-grid-column-fe179e6b\"><div class=\"gb-container gb-container-fe179e6b\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-abc4d030\">\n<div class=\"gb-grid-column gb-grid-column-a949118e\"><div class=\"gb-container gb-container-a949118e\">\n\n<p class=\"wp-block-paragraph\">Ce document a \u00e9t\u00e9 r\u00e9alis\u00e9 par le groupe de travail Durabilit\u00e9 de l\u2019UNES en \u00e9troite collaboration avec la FDD. Il contient les souhaits et les priorit\u00e9s des \u00e9tudiant\u00b7e\u00b7s suisses en terme de durabilit\u00e9 dans les hautes \u00e9coles. L\u2019objectif et l\u2019id\u00e9e de ce document de revendications est de mener une collaboration entre les diff\u00e9rentes parties prenantes de tous les domaines dans le milieu de l\u2019enseignement sup\u00e9rieur pour un avenir plus durable : notamment les \u00e9tudiant\u00b7e\u00b7s, le personnel des hautes \u00e9coles ainsi que les organes et institutions du milieu des hautes \u00e9coles. Comme toutes les hautes \u00e9coles se distinguent les unes des autres, les priorit\u00e9s et les besoins sont aussi diff\u00e9rents. Le contenu de ce document ne doit par cons\u00e9quent pas \u00eatre pris tel quel mais int\u00e9gr\u00e9 dans un document adapt\u00e9 \u00e0 la situation de la haute \u00e9cole. Les personnes qui souhaitent utiliser le document Word plut\u00f4t que le document pdf peuvent s\u2019adresser \u00e0 <a href=\"mailto:info@vss-unes.ch\">info@vss-unes.ch<\/a>.     <\/p>\n\n\n\n<a class=\"gb-button gb-button-2cb0c68e gb-button-text\" href=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/12\/2023-04-05_Nachhaltigkeitspapier_AG_def.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Base pour l\u2019\u00e9laboration de son propre document sur la durabilit\u00e9.<\/a>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-fd6f1191\"><div class=\"gb-container gb-container-fd6f1191\">\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"gb-block-image gb-block-image-b66e400d\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" class=\"gb-image gb-image-b66e400d\" src=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2024\/07\/image-7.png\" alt=\"\" title=\"image\"\/><\/figure>\n\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"gb-container gb-container-479719d5\">\n<div class=\"gb-container gb-container-0249a320 gb-accordion\">\n<div class=\"gb-container gb-container-cb0b523f gb-accordion__item gb-accordion__item-open\" data-transition=\"slide\">\n\n<button class=\"gb-button gb-button-fd11a91f gb-accordion__toggle gb-block-is-current\" id=\"gb-accordion-toggle-fd11a91f\"><span class=\"gb-button-text\"><strong>Postulez d\u00e8s maintenant ! Un nouveau fonds de projets vient d&#8217;\u00eatre lanc\u00e9 !<\/strong><\/span><span class=\"gb-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\" fill=\"currentColor\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"1em\" height=\"1em\" aria-hidden=\"true\" role=\"img\" class=\"gb-accordion__icon-open\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\" fill=\"currentColor\"><\/path><\/svg><\/span><\/button>\n\n\n<div id=\"gb-accordion-content-8046da6a\" class=\"gb-accordion__content\"><div class=\"gb-container gb-container-8046da6a\">\n<div class=\"gb-container gb-container-41930890\">\n\n<p class=\"wp-block-paragraph\"><strong>G\u00e9n\u00e9ralit\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le comit\u00e9 de l&#8217;UNES peut accorder un soutien \u00e0 des projets et \u00e0 des manifestations visant \u00e0 am\u00e9liorer la durabilit\u00e9 dans le contexte universitaire. En principe, le montant maximal allou\u00e9 par dossier est de 2 000 CHF. Il peut s&#8217;agir de subventions (couvrant un montant pr\u00e9cis) ou de garanties de couverture du d\u00e9ficit (couvrant le d\u00e9ficit jusqu&#8217;\u00e0 un montant maximal). L&#8217;accent est mis sur les petits projets, mais les projets de plus grande envergure peuvent \u00e9galement postuler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qui peut d\u00e9poser une demande ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les projets ou \u00e9v\u00e9nements organis\u00e9s par des \u00e9tudiant\u00b7e\u00b7s ou s&#8217;adressant \u00e0 des \u00e9tudiants peuvent faire l&#8217;objet d&#8217;une demande.<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-475811d1 gb-headline-text\"><strong>Quels sont les crit\u00e8res \u00e0 respecter ?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le projet a pour objectif de mettre davantage en avant les questions de d\u00e9veloppement durable dans le milieu des hautes \u00e9coles.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il a un objectif clair, qui peut \u00eatre bien communiqu\u00e9.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ce projet est politiquement neutre.<\/li>\n\n\n\n<li>Si tu as des questions, n&#8217;h\u00e9site pas \u00e0 contacter  <a href=\"mailto:info@vss-unes.ch\" target=\"_blank\" rel=\"noreferrer noopener\">info@vss-unes.ch<\/a>. Tu trouveras ci-dessous des explications d\u00e9taill\u00e9es sur la mani\u00e8re de d\u00e9poser une demande avec succ\u00e8s.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u<\/h2>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>G\u00e9n\u00e9ralit\u00e9s<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>R\u00e9daction de la demande<\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>D\u00e9p\u00f4t de la demande<\/li>\n<\/ol>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li>D\u00e9cision et versement<\/li>\n<\/ol>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Garantie de couverture du d\u00e9ficit ou cotisation fixe<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9daction de la demande<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Schreibe eine Einleitung, und beantworte im anschliessenden Fliesstext (max. 1-2 Seiten) mindestens folgende Fragen\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Qui s&#8217;occupe <\/strong>de l&#8217;organisation et de la facturation (personnes, organisation) ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Qui en b\u00e9n\u00e9ficie<\/strong> (nombre de personnes, public cible, lien avec les \u00e9tudiants, etc.) ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Quel est l&#8217;impact <\/strong>du projet (biodiversit\u00e9, \u00e9conomie circulaire, r\u00e9duction des \u00e9missions, sensibilisation, etc.) ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Quand <\/strong>le projet sera-t-il mis en \u0153uvre (pr\u00e9paration, r\u00e9alisation, suivi et cl\u00f4ture) ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pourquoi<\/strong> ce projet m\u00e9rite-t-il d&#8217;\u00eatre soutenu (objectifs, caract\u00e8re unique, impact\u2026) ?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puisque tu sollicites un soutien financier, merci de nous fournir \u00e9galement les informations suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Budget :<\/strong> pr\u00e9sentez un relev\u00e9 d\u00e9taill\u00e9 des recettes et des d\u00e9penses.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Autres bailleurs de fonds : <\/strong>note toutes les entit\u00e9s sollicit\u00e9es pour un soutien (organisations, entreprises, associations \u00e9tudiantes, universit\u00e9s, fondations culturelles, etc.) ainsi que l&#8217;\u00e9tat d&#8217;avancement des d\u00e9marches.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Montant demand\u00e9 :<\/strong> quel montant (et quelle contribution inconditionnelle ou garantie de couverture du d\u00e9ficit) est demand\u00e9 ?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mod\u00e8le<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le mod\u00e8le ci-dessous peut vous servir de guide (vous pouvez \u00e9galement utiliser vos propres mod\u00e8les, \u00e0 condition que toutes les informations n\u00e9cessaires y figurent).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2026\/06\/Demande_formulaire.pdf\">Demande formulaire<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9p\u00f4t de la demande<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Veille \u00e0 ce qu&#8217;aucune information ne manque. La transparence, \u00e7a vaut le coup.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Les candidatures peuvent \u00eatre envoy\u00e9es au format PDF \u00e0 l&#8217;adresse <\/strong><a href=\"mailto:info@vss-unes.ch\" target=\"_blank\" rel=\"noreferrer noopener\">info@vss-unes.ch<\/a><strong> aux quatre dates limites de l&#8217;ann\u00e9e :<\/strong> le 15 f\u00e9vrier, le 15 mai, le 15 septembre et le 15 novembre. (En 2026, une date limite exceptionnelle est fix\u00e9e au 30 juin 2026.)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si des questions se posent, le comit\u00e9 directeur de la VSS te contactera.<\/li>\n\n\n\n<li>&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9cision et versement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le comit\u00e9 directeur de la VSS communique sa d\u00e9cision dans un d\u00e9lai d&#8217;environ trois semaines \u00e0 compter du d\u00e9p\u00f4t de la demande. En cas de d\u00e9cision favorable, la VSS attend que son logo figure sur la publicit\u00e9 ou soit visible lors du d\u00e9roulement de l&#8217;\u00e9v\u00e9nement. Voir \u00e0 ce sujet : <a href=\"https:\/\/vss-unes-usu.atlassian.net\/wiki\/spaces\/Bureau\/pages\/57082079\/CI\" target=\"_blank\" rel=\"noreferrer noopener\">CI-Guidelines<\/a>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Envoyez, <strong>au plus tard deux mois apr\u00e8s la r\u00e9alisation du projet<\/strong>, une br\u00e8ve description et un d\u00e9compte complet \u00e0 l&#8217;adresse <a href=\"mailto:info@vss-unes.ch\" target=\"_blank\" rel=\"noreferrer noopener\">info@vss-unes.ch<\/a> afin que la subvention puisse \u00eatre vers\u00e9e. L&#8217;objet de l&#8217;e-mail doit \u00eatre le suivant : <strong>Versement au titre du fonds d\u00e9di\u00e9 aux projets de d\u00e9veloppement durable<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 d\u00e9faut<\/strong>, les aides financi\u00e8res ou les garanties de couverture du d\u00e9ficit accord\u00e9es expirent six mois apr\u00e8s leur mise en \u0153uvre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crit\u00e8res de s\u00e9lection<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les facteurs pouvant influencer une d\u00e9cision peuvent \u00eatre les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Combien de personnes b\u00e9n\u00e9ficient de ce projet et si le montant par personne est appropri\u00e9<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le projet a-t-il un objectif clair et quel est son impact en mati\u00e8re de d\u00e9veloppement durable ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Des d\u00e9marches ont-elles \u00e9t\u00e9 entreprises pour obtenir un financement par des fonds tiers provenant d&#8217;autres sources ?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si le projet b\u00e9n\u00e9ficie du soutien des \u00e9tudiants<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Garantie de d\u00e9ficit ou montant fixe ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Garantie contre le d\u00e9ficit : <\/strong>les recettes et les d\u00e9penses pr\u00e9vues dans le budget de ton projet s&#8217;\u00e9quilibrent et le solde devrait \u00eatre nul, mais il existe des incertitudes ou des risques (par exemple, une baisse de la fr\u00e9quentation et, par cons\u00e9quent, une diminution des recettes) et tu souhaites te pr\u00e9munir contre cette \u00e9ventualit\u00e9. Dans le cadre d&#8217;une garantie contre le d\u00e9ficit, la VSS prend en charge les co\u00fbts impr\u00e9vus \u00e0 hauteur du montant convenu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contribution forfaitaire :<\/strong> si un projet ou un \u00e9v\u00e9nement manque de moyens financiers (c&#8217;est-\u00e0-dire si les d\u00e9penses pr\u00e9vues sont sup\u00e9rieures aux recettes pr\u00e9vues, ou si le projet ne g\u00e9n\u00e8re aucune recette), il est possible de demander une contribution forfaitaire.<\/p>\n\n\n\n<a class=\"gb-button gb-button-7239560c gb-button-text\" href=\"https:\/\/vss-unes.ch\/wp-content\/uploads\/2026\/06\/Demande_formulaire.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Formulaire de demande<\/a>\n\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les hautes \u00e9coles assument une lourde responsabilit\u00e9 sociale. Elles forment les futur\u00b7e\u00b7s d\u00e9cideuses et d\u00e9cideurs, \u00e0 travers la recherche elles g\u00e9n\u00e8rent des connaissances et des innovations et elles influencent l\u2019opinion &#8230; <a title=\"Durabilit\u00e9\" class=\"read-more\" href=\"https:\/\/vss-unes.ch\/fr\/themen\/nachhaltigkeit\/\" aria-label=\"Read more about Durabilit\u00e9\">Read more<\/a><\/p>\n","protected":false},"featured_media":5924,"template":"","meta":{"inline_featured_image":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_links_to":"","_links_to_target":""},"topic-priorities":[84,87,85,82],"class_list":["post-4970","themen","type-themen","status-publish","has-post-thumbnail","hentry","topic-priorities-page-daccueil","topic-priorities-politique-des-hautes-ecoles","topic-priorities-priorites-thematiques-2023-2027","topic-priorities-sous-page"],"_links":{"self":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/themen\/4970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/themen"}],"about":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/types\/themen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/media\/5924"}],"wp:attachment":[{"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/media?parent=4970"}],"wp:term":[{"taxonomy":"topic-priorities","embeddable":true,"href":"https:\/\/vss-unes.ch\/fr\/wp-json\/wp\/v2\/topic-priorities?post=4970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}